{"id":673593,"date":"2023-12-04T13:43:10","date_gmt":"2023-12-04T11:43:10","guid":{"rendered":"https:\/\/hosfi.wpenginepowered.com\/wp-content\/uploads\/2023\/12\/nikolaos-juhlassa-lapsiperheita2022.jpg"},"modified":"2023-12-04T13:43:10","modified_gmt":"2023-12-04T11:43:10","slug":"nikolaos-juhlassa-lapsiperheita2022-2","status":"inherit","type":"attachment","link":"https:\/\/hos.fi\/sv\/nikolaos-juhlassa-lapsiperheita2022-2\/","title":{"rendered":"nikolaos-juhlassa-lapsiperheit\u00e42022"},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"class_list":["post-673593","attachment","type-attachment","status-inherit","hentry"],"acf":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/hos.fi\/wp-content\/uploads\/2023\/12\/nikolaos-juhlassa-lapsiperheita2022.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"1020\" height=\"681\" src=\"https:\/\/hos.fi\/wp-content\/uploads\/2023\/12\/nikolaos-juhlassa-lapsiperheita2022-1020x681.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/hos.fi\/wp-content\/uploads\/2023\/12\/nikolaos-juhlassa-lapsiperheita2022-1020x681.jpg 1020w, https:\/\/hos.fi\/wp-content\/uploads\/2023\/12\/nikolaos-juhlassa-lapsiperheita2022-1400x934.jpg 1400w, https:\/\/hos.fi\/wp-content\/uploads\/2023\/12\/nikolaos-juhlassa-lapsiperheita2022-768x513.jpg 768w, https:\/\/hos.fi\/wp-content\/uploads\/2023\/12\/nikolaos-juhlassa-lapsiperheita2022-1536x1025.jpg 1536w, https:\/\/hos.fi\/wp-content\/uploads\/2023\/12\/nikolaos-juhlassa-lapsiperheita2022-100x67.jpg 100w, https:\/\/hos.fi\/wp-content\/uploads\/2023\/12\/nikolaos-juhlassa-lapsiperheita2022-420x280.jpg 420w, https:\/\/hos.fi\/wp-content\/uploads\/2023\/12\/nikolaos-juhlassa-lapsiperheita2022.jpg 2048w\" sizes=\"auto, (max-width: 1020px) 100vw, 1020px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":2048,"height":1367,"file":"2023\/12\/nikolaos-juhlassa-lapsiperheita2022.jpg","sizes":{"medium":{"file":"nikolaos-juhlassa-lapsiperheita2022-1020x681.jpg","width":1020,"height":681,"mime_type":"image\/jpeg","source_url":"https:\/\/hos.fi\/wp-content\/uploads\/2023\/12\/nikolaos-juhlassa-lapsiperheita2022-1020x681.jpg"},"large":{"file":"nikolaos-juhlassa-lapsiperheita2022-1400x934.jpg","width":1400,"height":934,"mime_type":"image\/jpeg","source_url":"https:\/\/hos.fi\/wp-content\/uploads\/2023\/12\/nikolaos-juhlassa-lapsiperheita2022-1400x934.jpg"},"thumbnail":{"file":"nikolaos-juhlassa-lapsiperheita2022-480x480.jpg","width":480,"height":480,"mime_type":"image\/jpeg","source_url":"https:\/\/hos.fi\/wp-content\/uploads\/2023\/12\/nikolaos-juhlassa-lapsiperheita2022-480x480.jpg"},"medium_large":{"file":"nikolaos-juhlassa-lapsiperheita2022-768x513.jpg","width":768,"height":513,"mime_type":"image\/jpeg","source_url":"https:\/\/hos.fi\/wp-content\/uploads\/2023\/12\/nikolaos-juhlassa-lapsiperheita2022-768x513.jpg"},"1536x1536":{"file":"nikolaos-juhlassa-lapsiperheita2022-1536x1025.jpg","width":1536,"height":1025,"mime_type":"image\/jpeg","source_url":"https:\/\/hos.fi\/wp-content\/uploads\/2023\/12\/nikolaos-juhlassa-lapsiperheita2022-1536x1025.jpg"},"small thumbnail (100 x 100)":{"file":"nikolaos-juhlassa-lapsiperheita2022-100x67.jpg","width":100,"height":67,"mime_type":"image\/jpeg","source_url":"https:\/\/hos.fi\/wp-content\/uploads\/2023\/12\/nikolaos-juhlassa-lapsiperheita2022-100x67.jpg"},"portrait":{"file":"nikolaos-juhlassa-lapsiperheita2022-420x280.jpg","width":420,"height":280,"mime_type":"image\/jpeg","source_url":"https:\/\/hos.fi\/wp-content\/uploads\/2023\/12\/nikolaos-juhlassa-lapsiperheita2022-420x280.jpg"},"full":{"file":"nikolaos-juhlassa-lapsiperheita2022.jpg","width":2048,"height":1367,"mime_type":"image\/jpeg","source_url":"https:\/\/hos.fi\/wp-content\/uploads\/2023\/12\/nikolaos-juhlassa-lapsiperheita2022.jpg"}},"image_meta":{"aperture":"0","credit":"ANUMILLERRt","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/hos.fi\/wp-content\/uploads\/2023\/12\/nikolaos-juhlassa-lapsiperheita2022.jpg","filename":"nikolaos-juhlassa-lapsiperheita2022.jpg","filesize":617208,"_links":{"self":[{"href":"https:\/\/hos.fi\/sv\/wp-json\/wp\/v2\/media\/673593","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hos.fi\/sv\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/hos.fi\/sv\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/hos.fi\/sv\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/hos.fi\/sv\/wp-json\/wp\/v2\/comments?post=673593"}]}}